{"id":17289,"date":"2024-08-30T10:20:00","date_gmt":"2024-08-30T08:20:00","guid":{"rendered":"https:\/\/www.abf.eu\/albino\/?post_type=corsi&#038;p=17289"},"modified":"2026-05-13T12:39:54","modified_gmt":"2026-05-13T10:39:54","slug":"operatore-servizi-mensa","status":"publish","type":"corsi","link":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/","title":{"rendered":"Operatore servizi mensa"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.abf.eu\/clusone\/wp-content\/uploads\/sites\/2\/2023\/05\/FormatGOL-1024x118-2.jpg\" alt=\"\" class=\"wp-image-17515\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Con il corso di \u201cOperatore dei servizi mensa\u201d impari le basi per lavorare in mense, tavole calde e self-service!<\/strong><\/h3>\n\n\n\n<h5 class=\"wp-block-heading\">Obiettivi del corso<\/h5>\n\n\n\n<p>Il corso si rivolge a tutti coloro che intendono <strong>acquisire le competenze teoriche e pratiche per potersi avvicinare al mondo della ristorazione<\/strong> organizzata e industriale. L\u2019obiettivo fondamentale del percorso formativo \u00e8 infatti quello di <strong>formare una figura professionale che sia in grado di operare in autonomia all\u2019interno dei vari contesti operativi della ristorazione <\/strong>come mense, strutture ricettive e altre tipologie di riferimento.<br><br>L\u2019operatore del servizio mensa si occupa della <strong>preparazione e somministrazione degli alimenti <\/strong>con particolare attenzione ai clienti con bisogni specifici (allergie, intolleranze, celiachia), mantiene inoltre puliti ambienti, attrezzature e supporti garantendone la cura e il riordino secondo l\u2019organizzazione della cucina.<\/p>\n\n\n\n<p><strong>Le lezioni si svolgeranno all\u2019interno del moderno laboratorio di cucina di  \u201cDolci Sogni Liberi\u201d a Nembro.<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contenuti del corso<\/strong><\/h5>\n\n\n\n<p>Durante il corso verranno affrontate e seguenti tematiche:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La gestione ed il trattamento preventivo di prodotti alimentari nell\u2019ambito di processi controllati (HACCP);<\/li>\n\n\n\n<li>Tecniche di conservazione dei prodotti alimentari;<\/li>\n\n\n\n<li>Nozioni di igiene personale e di pulizia e igiene delle strutture e delle attrezzature;<\/li>\n\n\n\n<li>Tecniche di preparazione dei pasti;<\/li>\n\n\n\n<li>Tecniche di cottura degli alimenti;<\/li>\n\n\n\n<li>Preparazione delle singole diete particolari con attenzione ai men\u00f9 senza glutine e ai men\u00f9 per intolleranti;<\/li>\n\n\n\n<li>Consegna e servizio delle pietanze e successivo ritiro e riordino delle stesse.<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Requisiti d\u2019accesso<\/strong><\/h5>\n\n\n\n<p>Per poter accedere al corso di operatore dei servizi mensa \u00e8 necessario soddisfare i seguenti requisiti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Maggiore et\u00e0<\/li>\n\n\n\n<li>Buona conoscenza della lingua italiana<\/li>\n<\/ul>\n\n\n\n<p>Inoltre, \u00e8 necessario:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>essere in possesso dello SPID \u2013 Sistema Pubblico di Identit\u00e0 Digitale oppure<\/li>\n\n\n\n<li>essere in possesso della carta d\u2019identit\u00e0 elettronica \u201cCIE\u201d con i relativi codici rilasciati dalle autorit\u00e0 competenti. Se in possesso di CIE \u00e8 necessario scaricare sul proprio smartphone l\u2019applicazione \u201cCieSign\u201d per il riconoscimento del documento elettronico;<\/li>\n\n\n\n<li>aver installato sul proprio dispositivo digitale (smartphone o tablet) \u201cFirma LOM\u201d, l\u2019applicazione di Regione Lombardia per autenticarsi e convalidare le presenze giornaliere ai corsi.<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Orario delle lezioni e note<\/strong><\/h5>\n\n\n\n<p>Il corso ha una durata complessiva di 40 ore seguite da un ultimo incontro per l\u2019esame finale. Le lezioni si svolgeranno il luned\u00ec e <strong>gioved\u00ec mattina dalle 10.30 alle 13.30<\/strong> all\u2019interno del <strong>laboratorio di cucina di \u201cDolci Sogni Liberi\u201d a Nembro<\/strong>.<\/p>\n\n\n\n<p>A conclusione del percorso \u00e8 previsto il rilascio di un <strong>attestato di competenza<\/strong> che verr\u00e0 riconosciuto a seguito di una frequenza pari ad almeno il 75% delle ore totali e con il superamento dell&#8217;esame conclusivo finale. \u00c8 previsto altres\u00ec il rilascio dell&#8217;attestato di <strong>HACCP<\/strong> previo superamento del relativo esame.<\/p>\n\n\n\n<p>La quota di iscrizione per il corso di operatore dei servizi mensa \u00e8 di \u20ac 400.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">I disoccupati dai 16 ai 65 anni possono accedere gratuitamente al corso, se in possesso dei requisiti del Programma GOL.<\/h5>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\u00c8 possibile iscriversi al corso direttamente online dal sito ABF, cliccando sul pulsante \u201cISCRIZIONE\u201d in fondo a questa pagina.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>L\u2019effettiva partecipazione al corso \u00e8 subordinata alla ricezione di una mail di conferma<\/strong>.<\/h5>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contatti<\/strong><\/h5>\n\n\n\n<p>Per avere maggiori informazioni circa il nostro corso di Operatore dei servizi mensa non esitare a contattarci allo 035.3693703 o via mail all&#8217;indirizzo <a href=\"mailto:formazione.inclusione@abf.eu\">formazione.inclusione@abf.eu<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div id=\"linkcontent-block_66acdc9df0f98\" class=\"link-content \">\n    <a class='animated-arrow font-weight-bold' href='https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/AL-Operatore-servizi-mensa.pdf' target=\"_blank\">\n        <span class='the-arrow -left'>\n            <span class='shaft'><\/span>\n        <\/span>\n        <span class='main'>\n            <span class='text'>Scarica e condividi la locandina<\/span>\n            <span class='the-arrow -right'>\n                <span class='shaft'><\/span>\n            <\/span>\n        <\/span>\n    <\/a>\n<\/div>\n\n\n","protected":false},"featured_media":17313,"parent":0,"template":"","class_list":["post-17289","corsi","type-corsi","status-publish","has-post-thumbnail","hentry","macrocategoria-corsi-adulti","tipologia-corsi-cucina-e-ristorazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Operatore servizi mensa - Albino<\/title>\n<meta name=\"description\" content=\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Operatore servizi mensa - Albino\" \/>\n<meta property=\"og:description\" content=\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/\" \/>\n<meta property=\"og:site_name\" content=\"Albino\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:39:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/\",\"url\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/\",\"name\":\"Operatore servizi mensa - Albino\",\"isPartOf\":{\"@id\":\"https:\/\/www.abf.eu\/albino\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png\",\"datePublished\":\"2024-08-30T08:20:00+00:00\",\"dateModified\":\"2026-05-13T10:39:54+00:00\",\"description\":\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage\",\"url\":\"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png\",\"contentUrl\":\"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abf.eu\/albino\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Operatore servizi mensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abf.eu\/albino\/#website\",\"url\":\"https:\/\/www.abf.eu\/albino\/\",\"name\":\"Albino\",\"description\":\"Ecco un altro sito Abf siti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abf.eu\/albino\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Operatore servizi mensa - Albino","description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/","og_locale":"it_IT","og_type":"article","og_title":"Operatore servizi mensa - Albino","og_description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","og_url":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/","og_site_name":"Albino","article_modified_time":"2026-05-13T10:39:54+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/","url":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/","name":"Operatore servizi mensa - Albino","isPartOf":{"@id":"https:\/\/www.abf.eu\/albino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage"},"image":{"@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png","datePublished":"2024-08-30T08:20:00+00:00","dateModified":"2026-05-13T10:39:54+00:00","description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","breadcrumb":{"@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#primaryimage","url":"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png","contentUrl":"https:\/\/www.abf.eu\/albino\/wp-content\/uploads\/sites\/4\/2024\/08\/Addetto-servizi-mensa.png","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.abf.eu\/albino\/corsi\/operatore-servizi-mensa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abf.eu\/albino\/"},{"@type":"ListItem","position":2,"name":"Operatore servizi mensa"}]},{"@type":"WebSite","@id":"https:\/\/www.abf.eu\/albino\/#website","url":"https:\/\/www.abf.eu\/albino\/","name":"Albino","description":"Ecco un altro sito Abf siti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abf.eu\/albino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.abf.eu\/albino\/wp-json\/wp\/v2\/corsi\/17289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abf.eu\/albino\/wp-json\/wp\/v2\/corsi"}],"about":[{"href":"https:\/\/www.abf.eu\/albino\/wp-json\/wp\/v2\/types\/corsi"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/albino\/wp-json\/wp\/v2\/media\/17313"}],"wp:attachment":[{"href":"https:\/\/www.abf.eu\/albino\/wp-json\/wp\/v2\/media?parent=17289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}