{"id":25039,"date":"2026-02-11T12:43:23","date_gmt":"2026-02-11T11:43:23","guid":{"rendered":"https:\/\/www.abf.eu\/bergamo\/?post_type=corsi&#038;p=25039"},"modified":"2026-05-13T12:39:52","modified_gmt":"2026-05-13T10:39:52","slug":"henne-sopracciglia","status":"publish","type":"corsi","link":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/","title":{"rendered":"Henn\u00e8 sopracciglia"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Con il corso di Henn\u00e8 sopracciglia, ABF ti insegna come valorizzare al meglio lo sguardo<\/strong><\/h3>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Il corso dedicato a chi non rinuncia a uno sguardo indimenticabile<\/strong><\/h5>\n\n\n\n<p>Entra nel mondo dell\u2019estetica con una nuova prospettiva! <\/p>\n\n\n\n<p>Il nostro corso <strong>Henn\u00e8 Sopracciglia<\/strong> ti offre l\u2019opportunit\u00e0 di esplorare il potenziale trasformativo delle sopracciglia. Se sei un\u2019estetista esperta o un\u2019appassionata del beauty, questo percorso ti permetter\u00e0 di scoprire il segreto di sguardi intensi e incorniciati perfettamente. Lasciati guidare attraverso le sfumature dell\u2019henn\u00e8 e impara come valorizzare la bellezza naturale del viso. La nostra docente professionista, Savinkov Anna, ti condurr\u00e0 alla scoperta di questa tecnica artistica, dalla scelta dei prodotti all\u2019armonia della colorazione. Un viaggio formativo unico ti aspetta, pronto ad arricchire le tue competenze e il tuo bagaglio di bellezza. Prenota il tuo posto ora e preparati a trasformare sguardi con il Corso Henn\u00e8 Sopracciglia.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Cos\u2019\u00e8 l\u2019henn\u00e8 sopracciglia?<\/strong><\/h5>\n\n\n\n<p>L\u2019Henn\u00e8 sopracciglia, noto anche come Bio Tattoo, \u00e8 una <strong>tecnica di colorazione naturale<\/strong> con cui si tinge l\u2019arcata sopracciliare per enfatizzare lo sguardo. Con questo corso imparerai a mettere in risalto il viso donandogli un effetto illuminante ed intensificante, una combinazione perfetta per incorniciare gli occhi e avere sopracciglia definite e folte.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contenuti del corso Henn\u00e8 Sopracciglia<\/strong><\/h5>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nozioni sui prodotti per la colorazione delle sopracciglia<\/li>\n\n\n\n<li>A chi \u00e8 destinato il trattamento<\/li>\n\n\n\n<li>Composizione dell\u2019henn\u00e9<\/li>\n\n\n\n<li>Controindicazioni<\/li>\n\n\n\n<li>Raccomandazioni per il post trattamento<\/li>\n\n\n\n<li>Anatomia del pelo<\/li>\n\n\n\n<li>Struttura dell\u2019epidermide<\/li>\n\n\n\n<li>Lavoro con pelli difficili<\/li>\n\n\n\n<li>Colorimetria<\/li>\n\n\n\n<li>Studio della forma delle sopracciglia<\/li>\n\n\n\n<li>Progettazione della forma secondo le proporzioni del viso<\/li>\n\n\n\n<li>Dimostrazione del trattamento su modella<\/li>\n\n\n\n<li>Pratica su modella<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Ulteriori informazioni<\/strong><\/h5>\n\n\n\n<p>Le lezioni si svolgeranno il <strong>gioved\u00ec dalle 18.30 alle 21.30<\/strong>.<\/p>\n\n\n\n<p>Durante la parte pratica ciascuna allieva effettuer\u00e0 il trattamento di \u201cbio tattoo\u201d su una modella con la supervisione della docente.<\/p>\n\n\n\n<p>Informiamo che il costo del kit \u00e8 escluso dalla quota corso.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Docente<\/strong><\/h5>\n\n\n\n<p>La docente del corso di henn\u00e8 sopracciglia \u00e8 <a href=\"https:\/\/www.instagram.com\/laboratorio_di_immagine\">Savinkov Anna<\/a>, professionista del settore del benessere.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contatti<\/strong><\/h5>\n\n\n\n<p>Per avere ulteriori informazioni sul corso non esitate a contattarci allo 035 3693736 o mandate una mail a <em><a href=\"mailto:formazione.bergamo@abf.eu\">formazione.bergamo@abf.eu<\/a><\/em>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div id=\"linkcontent-block_6694d0421b8d9\" class=\"link-content \">\n    <a class='animated-arrow font-weight-bold' href='https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2025\/12\/BG-Henne-sopracciglia.pdf' target=\"_blank\">\n        <span class='the-arrow -left'>\n            <span class='shaft'><\/span>\n        <\/span>\n        <span class='main'>\n            <span class='text'>Scarica e condividi la locandina<\/span>\n            <span class='the-arrow -right'>\n                <span class='shaft'><\/span>\n            <\/span>\n        <\/span>\n    <\/a>\n<\/div>\n\n\n\n\n\n<p><\/p>\n","protected":false},"featured_media":19069,"parent":0,"template":"","class_list":["post-25039","corsi","type-corsi","status-publish","has-post-thumbnail","hentry","macrocategoria-corsi-adulti","tipologia-corsi-benessere-estetica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Henn\u00e8 sopracciglia - Bergamo<\/title>\n<meta name=\"description\" content=\"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Henn\u00e8 sopracciglia - Bergamo\" \/>\n<meta property=\"og:description\" content=\"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bergamo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/\",\"name\":\"Henn\u00e8 sopracciglia - Bergamo\",\"isPartOf\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png\",\"datePublished\":\"2026-02-11T11:43:23+00:00\",\"dateModified\":\"2026-05-13T10:39:52+00:00\",\"description\":\"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png\",\"contentUrl\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png\",\"width\":1000,\"height\":666,\"caption\":\"Colorazione Sopracciglia henn\u00e8\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abf.eu\/bergamo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Henn\u00e8 sopracciglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/#website\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/\",\"name\":\"Bergamo\",\"description\":\"Ecco un altro sito Abf siti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abf.eu\/bergamo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Henn\u00e8 sopracciglia - Bergamo","description":"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/","og_locale":"it_IT","og_type":"article","og_title":"Henn\u00e8 sopracciglia - Bergamo","og_description":"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.","og_url":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/","og_site_name":"Bergamo","article_modified_time":"2026-05-13T10:39:52+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/","url":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/","name":"Henn\u00e8 sopracciglia - Bergamo","isPartOf":{"@id":"https:\/\/www.abf.eu\/bergamo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage"},"image":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png","datePublished":"2026-02-11T11:43:23+00:00","dateModified":"2026-05-13T10:39:52+00:00","description":"ABF lancia il corso di Henn\u00e8 sopracciglia: scopri come incorniciare al meglio lo sguardo e rendere le sopracciglia definite e folte.","breadcrumb":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#primaryimage","url":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png","contentUrl":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2023\/04\/Progetto-senza-titolo.png","width":1000,"height":666,"caption":"Colorazione Sopracciglia henn\u00e8"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/henne-sopracciglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abf.eu\/bergamo\/"},{"@type":"ListItem","position":2,"name":"Henn\u00e8 sopracciglia"}]},{"@type":"WebSite","@id":"https:\/\/www.abf.eu\/bergamo\/#website","url":"https:\/\/www.abf.eu\/bergamo\/","name":"Bergamo","description":"Ecco un altro sito Abf siti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abf.eu\/bergamo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/corsi\/25039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/corsi"}],"about":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/types\/corsi"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/media\/19069"}],"wp:attachment":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/media?parent=25039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}