{"id":25423,"date":"2026-02-13T11:32:04","date_gmt":"2026-02-13T10:32:04","guid":{"rendered":"https:\/\/www.abf.eu\/bergamo\/?post_type=corsi&#038;p=25423"},"modified":"2026-05-13T12:39:50","modified_gmt":"2026-05-13T10:39:50","slug":"operatore-servizi-mensa-gol","status":"publish","type":"corsi","link":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/","title":{"rendered":"Operatore servizi mensa"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"72\" src=\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/image.jpeg\" alt=\"\" class=\"wp-image-25456\" srcset=\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/image.jpeg 1024w, https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/image-300x21.jpeg 300w, https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/image-768x54.jpeg 768w, https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/image-600x42.jpeg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Con il corso di \u201cOperatore servizi mensa\u201d impari le basi per lavorare in mense, tavole calde e self-service!<\/strong><\/h3>\n\n\n\n<h5 class=\"wp-block-heading\">Obiettivi del corso<\/h5>\n\n\n\n<p>Il corso si rivolge a tutti coloro che intendono acquisire le\u00a0<strong>competenze teoriche e pratiche per potersi avvicinare al mondo della ristorazione<\/strong>\u00a0organizzata e industriale. L\u2019obiettivo fondamentale del percorso formativo \u00e8 infatti quello di formare una figura professionale che sia in grado di\u00a0<strong>operare in autonomia all\u2019interno dei vari contesti operativi della ristorazione<\/strong>\u00a0come mense, strutture ricettive e altre tipologie di riferimento.<br><br>L\u2019operatore del servizio mensa si occupa della preparazione e somministrazione degli alimenti con particolare attenzione ai <strong>clienti con bisogni specifici<\/strong> (allergie, intolleranze, celiachia), mantiene inoltre puliti ambienti, attrezzature e supporti garantendone la cura e il riordino secondo l\u2019organizzazione della cucina.<\/p>\n\n\n\n<p>Le lezioni si svolgeranno all\u2019interno dell\u2019ampio e moderno laboratorio di cucina della sede ABF Bergamo, dotato di tutte le attrezzature e strumentazioni professionali necessarie per le diverse lavorazioni.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contenuti del corso<\/strong><\/h5>\n\n\n\n<p>Durante il corso verranno affrontate e seguenti tematiche:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La gestione ed il trattamento preventivo di prodotti alimentari nell\u2019ambito di processi controllati (HACCP);<\/li>\n\n\n\n<li>Tecniche di conservazione dei prodotti alimentari;<\/li>\n\n\n\n<li>Nozioni di igiene personale e di pulizia e igiene delle strutture e delle attrezzature;<\/li>\n\n\n\n<li>Tecniche di preparazione dei pasti;<\/li>\n\n\n\n<li>Tecniche di cottura degli alimenti;<\/li>\n\n\n\n<li>Preparazione delle singole diete particolari con attenzione ai men\u00f9 senza glutine e ai men\u00f9 per intolleranti;<\/li>\n\n\n\n<li>Consegna e servizio delle pietanze e successivo ritiro e riordino delle stesse.<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Requisiti d\u2019accesso<\/strong><\/h5>\n\n\n\n<p>Per poter accedere al corso di operatore dei servizi mensa \u00e8 necessario soddisfare i seguenti requisiti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Essere disoccupati in possesso dei requisiti di accesso al programma GOL<\/li>\n\n\n\n<li>Buona conoscenza della lingua italiana<\/li>\n<\/ul>\n\n\n\n<p>Inoltre, \u00e8 necessario:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>essere in possesso dello SPID \u2013 Sistema Pubblico di Identit\u00e0 Digitale oppure<\/li>\n\n\n\n<li>essere in possesso della carta d\u2019identit\u00e0 elettronica \u201cCIE\u201d con i relativi codici rilasciati dalle autorit\u00e0 competenti. Se in possesso di CIE \u00e8 necessario scaricare sul proprio smartphone l\u2019applicazione \u201cCieSign\u201d per il riconoscimento del documento elettronico;<\/li>\n\n\n\n<li>aver installato sul proprio dispositivo digitale (smartphone o tablet) \u201cFirma LOM\u201d, l\u2019applicazione di Regione Lombardia per autenticarsi e convalidare le presenze giornaliere ai corsi.<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\">Ulteriori informazioni<\/h5>\n\n\n\n<p>Il corso ha una durata complessiva di\u00a0<strong>40 ore<\/strong>\u00a0seguite da un ultimo incontro per l\u2019esame finale e le lezioni si svolgeranno presso la sede ABF di Bergamo il\u00a0<strong>luned\u00ec<\/strong>,\u00a0<strong>marted\u00ec<\/strong>, <strong>mercoled\u00ec<\/strong> e\u00a0<strong>gioved\u00ec<\/strong>\u00a0dalle\u00a0<strong>17.30<\/strong>\u00a0alle\u00a0<strong>21.30<\/strong>.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Il corso \u00e8 rivolto ai disoccupati dai 18 ai 65 anni in possesso dei requisiti del&nbsp;<a href=\"https:\/\/www.abf.eu\/programma-gol\/\">Programma GOL<\/a>.<\/h5>\n\n\n\n<p>Per ottenere l\u2019<strong>attestato di competenza<\/strong>&nbsp;\u00e8 richiesta una frequenza pari ad almeno il 70% delle ore totali. Al termine del corso \u00e8 previsto l\u2019esame finale, al superamento del quale verr\u00e0 rilasciato l\u2019attestato di competenza. \u00c8 previsto altres\u00ec il rilascio dell\u2019attestato di&nbsp;<strong>HACCP<\/strong>&nbsp;previo superamento del relativo esame.<\/p>\n\n\n\n<p>\u00c8 possibile iscriversi al corso direttamente online dal sito ABF, cliccando sul pulsante \u201cISCRIZIONE\u201d in fondo a questa pagina.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Sei interessato a questo corso ma non sei disoccupato?<\/h3>\n\n\n\n<p><strong><a href=\"mailto:formazione.bergamo@abf.eu\">Contattaci<\/a><\/strong>, saremo lieti di presentarti la nostra offerta formativa dedicata.<\/p>\n<\/blockquote>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contatti<\/strong><\/h5>\n\n\n\n<p>Per avere ulteriori informazioni sul corso chiama la segreteria allo 035&nbsp;3693&nbsp;734 o invia una mail a&nbsp;<a href=\"mailto:lavoro.bergamo@abf.eu.\" target=\"_blank\" rel=\"noreferrer noopener\">lavoro.bergamo@abf.eu<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div id=\"linkcontent-block_698b05e32d17f\" class=\"link-content \">\n    <a class='animated-arrow font-weight-bold' href='https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/BG-Operatore-dei-servizi-mensa.pdf' target=\"_blank\">\n        <span class='the-arrow -left'>\n            <span class='shaft'><\/span>\n        <\/span>\n        <span class='main'>\n            <span class='text'>Scarica e condividi la locandina!<\/span>\n            <span class='the-arrow -right'>\n                <span class='shaft'><\/span>\n            <\/span>\n        <\/span>\n    <\/a>\n<\/div>\n\n\n","protected":false},"featured_media":25497,"parent":0,"template":"","class_list":["post-25423","corsi","type-corsi","status-publish","has-post-thumbnail","hentry","macrocategoria-corsi-adulti","tipologia-corsi-cucina-e-ristorazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Operatore servizi mensa - Bergamo<\/title>\n<meta name=\"description\" content=\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Operatore servizi mensa - Bergamo\" \/>\n<meta property=\"og:description\" content=\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/\" \/>\n<meta property=\"og:site_name\" content=\"Bergamo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:39:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/\",\"name\":\"Operatore servizi mensa - Bergamo\",\"isPartOf\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png\",\"datePublished\":\"2026-02-13T10:32:04+00:00\",\"dateModified\":\"2026-05-13T10:39:50+00:00\",\"description\":\"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png\",\"contentUrl\":\"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abf.eu\/bergamo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Operatore servizi mensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abf.eu\/bergamo\/#website\",\"url\":\"https:\/\/www.abf.eu\/bergamo\/\",\"name\":\"Bergamo\",\"description\":\"Ecco un altro sito Abf siti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abf.eu\/bergamo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Operatore servizi mensa - Bergamo","description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/","og_locale":"it_IT","og_type":"article","og_title":"Operatore servizi mensa - Bergamo","og_description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","og_url":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/","og_site_name":"Bergamo","article_modified_time":"2026-05-13T10:39:50+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/","url":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/","name":"Operatore servizi mensa - Bergamo","isPartOf":{"@id":"https:\/\/www.abf.eu\/bergamo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage"},"image":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png","datePublished":"2026-02-13T10:32:04+00:00","dateModified":"2026-05-13T10:39:50+00:00","description":"Vuoi lavorare in self-service, mense o tavole calde? Il corso di operatore dei servizi mensa ti fornir\u00e0 tutte le conoscenze necessarie!","breadcrumb":{"@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#primaryimage","url":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png","contentUrl":"https:\/\/www.abf.eu\/bergamo\/wp-content\/uploads\/sites\/3\/2026\/02\/Addetto-servizi-mensa.png","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.abf.eu\/bergamo\/corsi\/operatore-servizi-mensa-gol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abf.eu\/bergamo\/"},{"@type":"ListItem","position":2,"name":"Operatore servizi mensa"}]},{"@type":"WebSite","@id":"https:\/\/www.abf.eu\/bergamo\/#website","url":"https:\/\/www.abf.eu\/bergamo\/","name":"Bergamo","description":"Ecco un altro sito Abf siti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abf.eu\/bergamo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/corsi\/25423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/corsi"}],"about":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/types\/corsi"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/media\/25497"}],"wp:attachment":[{"href":"https:\/\/www.abf.eu\/bergamo\/wp-json\/wp\/v2\/media?parent=25423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}