{"id":15386,"date":"2022-06-01T12:56:17","date_gmt":"2022-06-01T10:56:17","guid":{"rendered":"https:\/\/www.abf.eu\/curno\/?p=15386"},"modified":"2022-10-06T10:06:11","modified_gmt":"2022-10-06T08:06:11","slug":"chi-e-e-cosa-fa-il-tecnico-meccatronico","status":"publish","type":"post","link":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/","title":{"rendered":"Chi \u00e8 e cosa fa il tecnico meccatronico"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Non tutti sanno chi sia e cosa faccia il tecnico meccatronico. Spesso la sua definizione rimane nebulosa, avvolta nel mistero. Noi siamo qui per risolvere questo problema e schiarirvi le idee.<\/h3>\n\n\n\n<p>Il tecnico meccatronico \u00e8 una figura particolarmente complessa e poliedrica. E&#8217; in grado di integrare tre diverse discipline: l&#8217;elettronica, la meccanica e l&#8217;informatica. Il suo compito \u00e8 quindi quello di coniugare i sistemi elettrici, informatici e meccanici.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Competenze specifiche<\/h5>\n\n\n\n<p>Il tecnico meccatronico progetta gli impianti industriali, dalla teoria alla messa in pratica, cercando di mantenere il pi\u00f9 possibile gli obiettivi iniziali. <\/p>\n\n\n\n<p>Pu\u00f2 inoltre intervenire su impianti meccanici costruiti da altri, con il compito di migliorarli e ottimizzarli; la riduzione delle spese sugli scarti dei materiali o sui consumi energetici possono essere degli esempi di ci\u00f2 che gli viene richiesto.<\/p>\n\n\n\n<p>In generale, quindi, le sue mansioni vanno dalla progettazione e l\u2019assemblaggio dei vari componenti alla manutenzione periodica di impianti industriali. Questo fa del tecnico meccatronico anche una sorta di supervisore: individua guasti o imperfezioni di un macchinario e si attiva per risolverli. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Sbocchi professionali<\/h5>\n\n\n\n<p>Proiettiamoci ora la futuro: dopo gli studi dove trovare lavoro?<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Grazie alla poliedricit\u00e0 che gli appartiene, il tecnico meccatronico trova il suo principale impiego nel settore della robotica, ovvero uno dei pi\u00f9 all\u2019avanguardia e di prospettiva.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.11.32.jpeg\" alt=\"\" class=\"wp-image-15402\" width=\"425\" height=\"180\" srcset=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.11.32.jpeg 1024w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.11.32-300x128.jpeg 300w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.11.32-768x327.jpeg 768w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.11.32-600x255.jpeg 600w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Ovviamente, come detto in precedenza, il tecnico meccatronico pu\u00f2 anche operare ad un livello pi\u00f9 basso, occupandosi per esempio dell\u2019automazione dei macchinari industriali nelle fabbriche o dei sistemi di movimento nei veicoli. Pu\u00f2 lavorare in officine meccaniche, nel settore automotive, nel settore navale, in aziende metalmeccaniche&#8230; .<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.13.10.jpeg\" alt=\"\" class=\"wp-image-15403\" width=\"420\" height=\"236\" srcset=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.13.10.jpeg 768w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.13.10-300x169.jpeg 300w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.13.10-600x338.jpeg 600w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>In ogni caso, dato il ruolo strategico e la formazione altamente professionale di questa figura, le occasioni di carriera sono molteplici.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Campi di applicazione<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Automazione<\/strong>: questo termine indica la tecnologia che usa sistemi di controllo per gestire macchine e processi, riducendo la necessit\u00e0 dell&#8217;intervento umano. Si rende necessaria in operazioni ripetitive o complesse, per maggiore sicurezza o semplicemente maggiore comodit\u00e0.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Sensori<\/strong>: dispositivi che si trovano in diretta interazione con il sistema misurato. Questo componente effettua la conversione di una grandezza di una certa natura in una di natura diversa. Comunemente vengono classificati proprio in base al tipo di grandezza fisica che misurano: ad esempio sensori ottici (fotocellule), a infrarossi, di suono (microfoni), di temperatura (termometri)&#8230; .<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Domotica<\/strong>: settore che si occupa dello studio delle tecnologie adatte a migliorare la qualit\u00e0 della vita nella casa. E&#8217; un&#8217;area fortemente interdisciplinare perch\u00e9 richiede l&#8217;apporto di molte tecnologie e professionalit\u00e0, tra cui automazione, elettrotecnica, elettronica, informatica, telecomunicazioni e design.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>PLC<\/strong>: Controllore Logico Programmabile, computer specializzato nella gestione e nel controllo di processi industriali. Elabora i segnali digitali ed analogici provenienti da sensori e diretti agli attuatori presenti in un impianto industriale; la sua struttura viene adattata in base al processo da automatizzare. Nel tempo, con la progressiva miniaturizzazione della componentistica elettronica e la diminuzione dei costi, \u00e8 entrato anche nell&#8217;uso domestico.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-1-1.jpeg\" alt=\"\" class=\"wp-image-15430\" width=\"558\" height=\"361\" srcset=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-1-1.jpeg 640w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-1-1-300x194.jpeg 300w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-1-1-600x388.jpeg 600w\" sizes=\"auto, (max-width: 558px) 100vw, 558px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-2.jpeg\" alt=\"\" class=\"wp-image-15431\" width=\"590\" height=\"311\" srcset=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-2.jpeg 800w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-2-300x158.jpeg 300w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-2-768x405.jpeg 768w, https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.25-2-600x317.jpeg 600w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><em>Sui nostri profili social, tramite brevi video di presentazione con professori e studenti, stiamo promuovendo il nostro corso di meccatronica. Vi consiglio di <a href=\"https:\/\/instagram.com\/abf.curno?igshid=YmMyMTA2M2Y=\">seguirci<\/a> (siamo anche su <a href=\"https:\/\/www.facebook.com\/cfpcurnoalmenno\/\">Facebook<\/a>!) se volete vedere i nostri fantastici laboratori e gli strumenti professionali che vi possiamo offrire<\/em>.<\/p>\n\n\n\n<p>S<em>e volete approfondire le materie studiate o avere ulteriori dettagli sul nostro corso vi consiglio di cliccare <a href=\"https:\/\/www.abf.eu\/curno\/corsi\/operatore-meccatronico\/\">qui<\/a>.<\/em><\/p>\n\n\n\n<p>Se <em>invece volete visitare la scuola e incontrare il nostro coordinatore <a href=\"https:\/\/www.abf.eu\/curno\/contatti-e-referenti\/\">contattaci<\/a>! A presto!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non tutti sanno chi sia e cosa faccia il tecnico<\/p>\n","protected":false},"author":29,"featured_media":15429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chi \u00e8 e cosa fa il tecnico meccatronico - Curno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chi \u00e8 e cosa fa il tecnico meccatronico - Curno\" \/>\n<meta property=\"og:description\" content=\"Non tutti sanno chi sia e cosa faccia il tecnico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/\" \/>\n<meta property=\"og:site_name\" content=\"Curno\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T10:56:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T08:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valentinalamperti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"valentinalamperti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/\",\"url\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/\",\"name\":\"Chi \u00e8 e cosa fa il tecnico meccatronico - Curno\",\"isPartOf\":{\"@id\":\"https:\/\/www.abf.eu\/curno\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg\",\"datePublished\":\"2022-06-01T10:56:17+00:00\",\"dateModified\":\"2022-10-06T08:06:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/80f5096f53d6372bff33bd37524f0d97\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage\",\"url\":\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg\",\"contentUrl\":\"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abf.eu\/curno\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chi \u00e8 e cosa fa il tecnico meccatronico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abf.eu\/curno\/#website\",\"url\":\"https:\/\/www.abf.eu\/curno\/\",\"name\":\"Curno\",\"description\":\"Ecco un altro sito Abf siti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abf.eu\/curno\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/80f5096f53d6372bff33bd37524f0d97\",\"name\":\"valentinalamperti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d11c73440097a8b15885a92d8badf2db088be4f45591c073a5b9afd6e287e84f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d11c73440097a8b15885a92d8badf2db088be4f45591c073a5b9afd6e287e84f?s=96&d=mm&r=g\",\"caption\":\"valentinalamperti\"},\"url\":\"https:\/\/www.abf.eu\/curno\/author\/valentinalamperti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chi \u00e8 e cosa fa il tecnico meccatronico - Curno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/","og_locale":"it_IT","og_type":"article","og_title":"Chi \u00e8 e cosa fa il tecnico meccatronico - Curno","og_description":"Non tutti sanno chi sia e cosa faccia il tecnico","og_url":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/","og_site_name":"Curno","article_published_time":"2022-06-01T10:56:17+00:00","article_modified_time":"2022-10-06T08:06:11+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg","type":"image\/jpeg"}],"author":"valentinalamperti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"valentinalamperti","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/","url":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/","name":"Chi \u00e8 e cosa fa il tecnico meccatronico - Curno","isPartOf":{"@id":"https:\/\/www.abf.eu\/curno\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage"},"image":{"@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg","datePublished":"2022-06-01T10:56:17+00:00","dateModified":"2022-10-06T08:06:11+00:00","author":{"@id":"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/80f5096f53d6372bff33bd37524f0d97"},"breadcrumb":{"@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#primaryimage","url":"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg","contentUrl":"https:\/\/www.abf.eu\/curno\/wp-content\/uploads\/sites\/5\/2022\/06\/WhatsApp-Image-2022-06-01-at-12.38.24.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.abf.eu\/curno\/chi-e-e-cosa-fa-il-tecnico-meccatronico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abf.eu\/curno\/"},{"@type":"ListItem","position":2,"name":"Chi \u00e8 e cosa fa il tecnico meccatronico"}]},{"@type":"WebSite","@id":"https:\/\/www.abf.eu\/curno\/#website","url":"https:\/\/www.abf.eu\/curno\/","name":"Curno","description":"Ecco un altro sito Abf siti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abf.eu\/curno\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/80f5096f53d6372bff33bd37524f0d97","name":"valentinalamperti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abf.eu\/curno\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d11c73440097a8b15885a92d8badf2db088be4f45591c073a5b9afd6e287e84f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d11c73440097a8b15885a92d8badf2db088be4f45591c073a5b9afd6e287e84f?s=96&d=mm&r=g","caption":"valentinalamperti"},"url":"https:\/\/www.abf.eu\/curno\/author\/valentinalamperti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/posts\/15386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/comments?post=15386"}],"version-history":[{"count":20,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/posts\/15386\/revisions"}],"predecessor-version":[{"id":15596,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/posts\/15386\/revisions\/15596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/media\/15429"}],"wp:attachment":[{"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/media?parent=15386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/categories?post=15386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abf.eu\/curno\/wp-json\/wp\/v2\/tags?post=15386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}